{"id":11752,"date":"2026-07-14T09:40:18","date_gmt":"2026-07-14T08:40:18","guid":{"rendered":"https:\/\/maslowcapital.com\/?p=11752"},"modified":"2026-07-14T09:40:18","modified_gmt":"2026-07-14T08:40:18","slug":"maslow-capital-financia-la-primera-cartera-hotelera-de-selecto-la-nueva-plataforma-hotelera-de-tikehau-capital-en-iberia-con-un-valor-bruto-de-desarrollo-superior-a-200-millones-de-euros","status":"publish","type":"post","link":"https:\/\/maslowcapital.com\/es\/blog\/2026\/07\/14\/maslow-capital-financia-la-primera-cartera-hotelera-de-selecto-la-nueva-plataforma-hotelera-de-tikehau-capital-en-iberia-con-un-valor-bruto-de-desarrollo-superior-a-200-millones-de-euros\/","title":{"rendered":"Maslow Capital financia la primera cartera hotelera de Selecto, la nueva plataforma hotelera de Tikehau Capital en Iberia, con un valor bruto de desarrollo superior a 200 millones de euros"},"content":{"rendered":"<ul>\n<li><strong>La operaci\u00f3n refleja el creciente protagonismo de la financiaci\u00f3n alternativa para impulsar nuevos desarrollos inmobiliarios en activos operativos<\/strong><\/li>\n<\/ul>\n<p>Maslow Capital, proveedor paneuropeo l\u00edder de financiaci\u00f3n inmobiliaria especializada, ha proporcionado financiaci\u00f3n senior para respaldar la primera cartera hotelera ib\u00e9rica de Selecto.<\/p>\n<p><img decoding=\"async\" class=\"alignnone size-medium wp-image-11557\" src=\"https:\/\/maslowcapital.com\/wp-content\/uploads\/2026\/06\/Malaga-Palacio-de-Congresos-large-2-600x450.png\" alt=\"\" width=\"600\" height=\"450\" srcset=\"https:\/\/maslowcapital.com\/wp-content\/uploads\/2026\/06\/Malaga-Palacio-de-Congresos-large-2-600x450.png 600w, https:\/\/maslowcapital.com\/wp-content\/uploads\/2026\/06\/Malaga-Palacio-de-Congresos-large-2-1400x1050.png 1400w, https:\/\/maslowcapital.com\/wp-content\/uploads\/2026\/06\/Malaga-Palacio-de-Congresos-large-2-768x576.png 768w, https:\/\/maslowcapital.com\/wp-content\/uploads\/2026\/06\/Malaga-Palacio-de-Congresos-large-2-1536x1152.png 1536w, https:\/\/maslowcapital.com\/wp-content\/uploads\/2026\/06\/Malaga-Palacio-de-Congresos-large-2-2048x1536.png 2048w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/p>\n<p>Selecto es una nueva plataforma hotelera centrada en el segmento de hoteles urbanos de servicios limitados en la Pen\u00ednsula Ib\u00e9rica, lanzada por Tikehau Capital junto con Quest Capital. La cartera comprende cuatro proyectos en Madrid, M\u00e1laga y Barcelona, con un valor bruto de desarrollo conjunto superior a 200 millones de euros.<\/p>\n<p>Los activos se ubican en MadBit y Las Tablas, en Madrid; en la zona de FYCMA, en M\u00e1laga; y en L\u2019Hospitalet de Llobregat, en Barcelona, junto a Plaza Europa y Fira Barcelona. Los hoteles operar\u00e1n bajo la marca Holiday Inn Express a trav\u00e9s de un acuerdo de franquicia con IHG Hotels &amp; Resorts.<\/p>\n<p>El proyecto de MadBit, en Madrid, ya ha entrado en fase de construcci\u00f3n y representa el primer activo de la plataforma en pasar a fase de desarrollo.<\/p>\n<p><img decoding=\"async\" class=\"alignnone size-medium wp-image-11525\" src=\"https:\/\/maslowcapital.com\/wp-content\/uploads\/2026\/06\/94613af0-6fd4-4f76-8cf1-b9f7c52f2a06-600x450.png\" alt=\"\" width=\"600\" height=\"450\" srcset=\"https:\/\/maslowcapital.com\/wp-content\/uploads\/2026\/06\/94613af0-6fd4-4f76-8cf1-b9f7c52f2a06-600x450.png 600w, https:\/\/maslowcapital.com\/wp-content\/uploads\/2026\/06\/94613af0-6fd4-4f76-8cf1-b9f7c52f2a06-1400x1050.png 1400w, https:\/\/maslowcapital.com\/wp-content\/uploads\/2026\/06\/94613af0-6fd4-4f76-8cf1-b9f7c52f2a06-768x576.png 768w, https:\/\/maslowcapital.com\/wp-content\/uploads\/2026\/06\/94613af0-6fd4-4f76-8cf1-b9f7c52f2a06.png 1448w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/p>\n<p>La operaci\u00f3n refuerza el papel de Maslow Capital como socio financiero especializado para plataformas inmobiliarias, inversores institucionales y operadores especializados en toda Europa. Asimismo, refleja la creciente demanda de activos inmobiliarios operativos en Espa\u00f1a, especialmente aquellos vinculados a modelos eficientes y escalables, como los hoteles urbanos.<\/p>\n<p>En los \u00faltimos meses, Maslow Capital ha respaldado proyectos de referencia en los sectores hotelero, log\u00edstico, living y otros activos inmobiliarios operativos, aportando soluciones de financiaci\u00f3n adaptadas a estructuras complejas y a los requisitos espec\u00edficos de cada proyecto. Esta actividad pone de manifiesto el papel cada vez m\u00e1s relevante de la financiaci\u00f3n alternativa como v\u00eda complementaria para hacer posibles nuevos desarrollos inmobiliarios y acelerar la creaci\u00f3n de valor en activos con s\u00f3lidos fundamentales de demanda.<\/p>\n<p><strong>Emilio Silvestre, Managing Director de Maslow Capital en Espa\u00f1a, afirm\u00f3:<\/strong> <em>\u00abEsta operaci\u00f3n refleja nuestro compromiso con el respaldo a plataformas con un claro potencial de crecimiento y activos alineados con la evoluci\u00f3n de las din\u00e1micas del mercado inmobiliario. El segmento hotelero urbano ofrece oportunidades atractivas en Espa\u00f1a, impulsadas por una combinaci\u00f3n de demanda, profesionalizaci\u00f3n y modelos operativos escalables. Selecto re\u00fane muchos de los elementos que buscamos en nuestros socios: una estrategia clara, operadores l\u00edderes y proyectos con potencial a largo plazo\u00bb.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La operaci\u00f3n refleja el creciente protagonismo de la financiaci\u00f3n alternativa para impulsar nuevos desarrollos inmobiliarios en activos operativos Maslow Capital, proveedor paneuropeo l\u00edder de financiaci\u00f3n inmobiliaria especializada, ha proporcionado financiaci\u00f3n senior para respaldar la primera [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":11557,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[195],"tags":[],"class_list":["post-11752","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categorizar"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Maslow Capital financia la primera cartera hotelera de Selecto, la nueva plataforma hotelera de Tikehau Capital en Iberia, con un valor bruto de desarrollo superior a 200 millones de euros | Maslow Capital<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/maslowcapital.com\/es\/blog\/2026\/07\/14\/maslow-capital-financia-la-primera-cartera-hotelera-de-selecto-la-nueva-plataforma-hotelera-de-tikehau-capital-en-iberia-con-un-valor-bruto-de-desarrollo-superior-a-200-millones-de-euros\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Maslow Capital financia la primera cartera hotelera de Selecto, la nueva plataforma hotelera de Tikehau Capital en Iberia, con un valor bruto de desarrollo superior a 200 millones de euros | Maslow Capital\" \/>\n<meta property=\"og:description\" content=\"La operaci\u00f3n refleja el creciente protagonismo de la financiaci\u00f3n alternativa para impulsar nuevos desarrollos inmobiliarios en activos operativos Maslow Capital, proveedor paneuropeo l\u00edder de financiaci\u00f3n inmobiliaria especializada, ha proporcionado financiaci\u00f3n senior para respaldar la primera [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/maslowcapital.com\/es\/blog\/2026\/07\/14\/maslow-capital-financia-la-primera-cartera-hotelera-de-selecto-la-nueva-plataforma-hotelera-de-tikehau-capital-en-iberia-con-un-valor-bruto-de-desarrollo-superior-a-200-millones-de-euros\/\" \/>\n<meta property=\"og:site_name\" content=\"Maslow Capital\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-14T08:40:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/maslowcapital.com\/wp-content\/uploads\/2026\/06\/Malaga-Palacio-de-Congresos-large-2-768x576.png\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Richard Wojcik\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@maslowcapital\" \/>\n<meta name=\"twitter:site\" content=\"@maslowcapital\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Richard Wojcik\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/maslowcapital.com\\\/es\\\/blog\\\/2026\\\/07\\\/14\\\/maslow-capital-financia-la-primera-cartera-hotelera-de-selecto-la-nueva-plataforma-hotelera-de-tikehau-capital-en-iberia-con-un-valor-bruto-de-desarrollo-superior-a-200-millones-de-euros\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/maslowcapital.com\\\/es\\\/blog\\\/2026\\\/07\\\/14\\\/maslow-capital-financia-la-primera-cartera-hotelera-de-selecto-la-nueva-plataforma-hotelera-de-tikehau-capital-en-iberia-con-un-valor-bruto-de-desarrollo-superior-a-200-millones-de-euros\\\/\"},\"author\":{\"name\":\"Richard Wojcik\",\"@id\":\"https:\\\/\\\/maslowcapital.com\\\/#\\\/schema\\\/person\\\/99ff00ee026846905cc292b48b909306\"},\"headline\":\"Maslow Capital financia la primera cartera hotelera de Selecto, la nueva plataforma hotelera de Tikehau Capital en Iberia, con un valor bruto de desarrollo superior a 200 millones de euros\",\"datePublished\":\"2026-07-14T08:40:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/maslowcapital.com\\\/es\\\/blog\\\/2026\\\/07\\\/14\\\/maslow-capital-financia-la-primera-cartera-hotelera-de-selecto-la-nueva-plataforma-hotelera-de-tikehau-capital-en-iberia-con-un-valor-bruto-de-desarrollo-superior-a-200-millones-de-euros\\\/\"},\"wordCount\":434,\"publisher\":{\"@id\":\"https:\\\/\\\/maslowcapital.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/maslowcapital.com\\\/es\\\/blog\\\/2026\\\/07\\\/14\\\/maslow-capital-financia-la-primera-cartera-hotelera-de-selecto-la-nueva-plataforma-hotelera-de-tikehau-capital-en-iberia-con-un-valor-bruto-de-desarrollo-superior-a-200-millones-de-euros\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/maslowcapital.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Malaga-Palacio-de-Congresos-large-2-scaled.png\",\"articleSection\":[\"Sin categorizar\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/maslowcapital.com\\\/es\\\/blog\\\/2026\\\/07\\\/14\\\/maslow-capital-financia-la-primera-cartera-hotelera-de-selecto-la-nueva-plataforma-hotelera-de-tikehau-capital-en-iberia-con-un-valor-bruto-de-desarrollo-superior-a-200-millones-de-euros\\\/\",\"url\":\"https:\\\/\\\/maslowcapital.com\\\/es\\\/blog\\\/2026\\\/07\\\/14\\\/maslow-capital-financia-la-primera-cartera-hotelera-de-selecto-la-nueva-plataforma-hotelera-de-tikehau-capital-en-iberia-con-un-valor-bruto-de-desarrollo-superior-a-200-millones-de-euros\\\/\",\"name\":\"Maslow Capital financia la primera cartera hotelera de Selecto, la nueva plataforma hotelera de Tikehau Capital en Iberia, con un valor bruto de desarrollo superior a 200 millones de euros | Maslow Capital\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/maslowcapital.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/maslowcapital.com\\\/es\\\/blog\\\/2026\\\/07\\\/14\\\/maslow-capital-financia-la-primera-cartera-hotelera-de-selecto-la-nueva-plataforma-hotelera-de-tikehau-capital-en-iberia-con-un-valor-bruto-de-desarrollo-superior-a-200-millones-de-euros\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/maslowcapital.com\\\/es\\\/blog\\\/2026\\\/07\\\/14\\\/maslow-capital-financia-la-primera-cartera-hotelera-de-selecto-la-nueva-plataforma-hotelera-de-tikehau-capital-en-iberia-con-un-valor-bruto-de-desarrollo-superior-a-200-millones-de-euros\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/maslowcapital.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Malaga-Palacio-de-Congresos-large-2-scaled.png\",\"datePublished\":\"2026-07-14T08:40:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/maslowcapital.com\\\/es\\\/blog\\\/2026\\\/07\\\/14\\\/maslow-capital-financia-la-primera-cartera-hotelera-de-selecto-la-nueva-plataforma-hotelera-de-tikehau-capital-en-iberia-con-un-valor-bruto-de-desarrollo-superior-a-200-millones-de-euros\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/maslowcapital.com\\\/es\\\/blog\\\/2026\\\/07\\\/14\\\/maslow-capital-financia-la-primera-cartera-hotelera-de-selecto-la-nueva-plataforma-hotelera-de-tikehau-capital-en-iberia-con-un-valor-bruto-de-desarrollo-superior-a-200-millones-de-euros\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/maslowcapital.com\\\/es\\\/blog\\\/2026\\\/07\\\/14\\\/maslow-capital-financia-la-primera-cartera-hotelera-de-selecto-la-nueva-plataforma-hotelera-de-tikehau-capital-en-iberia-con-un-valor-bruto-de-desarrollo-superior-a-200-millones-de-euros\\\/#primaryimage\",\"url\":\"https:\\\/\\\/maslowcapital.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Malaga-Palacio-de-Congresos-large-2-scaled.png\",\"contentUrl\":\"https:\\\/\\\/maslowcapital.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Malaga-Palacio-de-Congresos-large-2-scaled.png\",\"width\":2560,\"height\":1920},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/maslowcapital.com\\\/es\\\/blog\\\/2026\\\/07\\\/14\\\/maslow-capital-financia-la-primera-cartera-hotelera-de-selecto-la-nueva-plataforma-hotelera-de-tikehau-capital-en-iberia-con-un-valor-bruto-de-desarrollo-superior-a-200-millones-de-euros\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/maslowcapital.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Maslow Capital financia la primera cartera hotelera de Selecto, la nueva plataforma hotelera de Tikehau Capital en Iberia, con un valor bruto de desarrollo superior a 200 millones de euros\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/maslowcapital.com\\\/#website\",\"url\":\"https:\\\/\\\/maslowcapital.com\\\/\",\"name\":\"Maslow Capital\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/maslowcapital.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/maslowcapital.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/maslowcapital.com\\\/#organization\",\"name\":\"Maslow Capital\",\"url\":\"https:\\\/\\\/maslowcapital.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/maslowcapital.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/maslowcapital.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/maslow-capital-logo.png\",\"contentUrl\":\"https:\\\/\\\/maslowcapital.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/maslow-capital-logo.png\",\"width\":328,\"height\":242,\"caption\":\"Maslow Capital\"},\"image\":{\"@id\":\"https:\\\/\\\/maslowcapital.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/maslowcapital\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/maslow-capital-llp\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/maslowcapital.com\\\/#\\\/schema\\\/person\\\/99ff00ee026846905cc292b48b909306\",\"name\":\"Richard Wojcik\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ab0bbd80fd18e2a52852d277779a5c3bef2d48efee7dace58782d64f83111445?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ab0bbd80fd18e2a52852d277779a5c3bef2d48efee7dace58782d64f83111445?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ab0bbd80fd18e2a52852d277779a5c3bef2d48efee7dace58782d64f83111445?s=96&d=mm&r=g\",\"caption\":\"Richard Wojcik\"},\"url\":\"https:\\\/\\\/maslowcapital.com\\\/es\\\/blog\\\/author\\\/richardw\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Maslow Capital financia la primera cartera hotelera de Selecto, la nueva plataforma hotelera de Tikehau Capital en Iberia, con un valor bruto de desarrollo superior a 200 millones de euros | Maslow Capital","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/maslowcapital.com\/es\/blog\/2026\/07\/14\/maslow-capital-financia-la-primera-cartera-hotelera-de-selecto-la-nueva-plataforma-hotelera-de-tikehau-capital-en-iberia-con-un-valor-bruto-de-desarrollo-superior-a-200-millones-de-euros\/","og_locale":"es_ES","og_type":"article","og_title":"Maslow Capital financia la primera cartera hotelera de Selecto, la nueva plataforma hotelera de Tikehau Capital en Iberia, con un valor bruto de desarrollo superior a 200 millones de euros | Maslow Capital","og_description":"La operaci\u00f3n refleja el creciente protagonismo de la financiaci\u00f3n alternativa para impulsar nuevos desarrollos inmobiliarios en activos operativos Maslow Capital, proveedor paneuropeo l\u00edder de financiaci\u00f3n inmobiliaria especializada, ha proporcionado financiaci\u00f3n senior para respaldar la primera [&hellip;]","og_url":"https:\/\/maslowcapital.com\/es\/blog\/2026\/07\/14\/maslow-capital-financia-la-primera-cartera-hotelera-de-selecto-la-nueva-plataforma-hotelera-de-tikehau-capital-en-iberia-con-un-valor-bruto-de-desarrollo-superior-a-200-millones-de-euros\/","og_site_name":"Maslow Capital","article_published_time":"2026-07-14T08:40:18+00:00","og_image":[{"width":768,"height":576,"url":"https:\/\/maslowcapital.com\/wp-content\/uploads\/2026\/06\/Malaga-Palacio-de-Congresos-large-2-768x576.png","type":"image\/png"}],"author":"Richard Wojcik","twitter_card":"summary_large_image","twitter_creator":"@maslowcapital","twitter_site":"@maslowcapital","twitter_misc":{"Escrito por":"Richard Wojcik","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/maslowcapital.com\/es\/blog\/2026\/07\/14\/maslow-capital-financia-la-primera-cartera-hotelera-de-selecto-la-nueva-plataforma-hotelera-de-tikehau-capital-en-iberia-con-un-valor-bruto-de-desarrollo-superior-a-200-millones-de-euros\/#article","isPartOf":{"@id":"https:\/\/maslowcapital.com\/es\/blog\/2026\/07\/14\/maslow-capital-financia-la-primera-cartera-hotelera-de-selecto-la-nueva-plataforma-hotelera-de-tikehau-capital-en-iberia-con-un-valor-bruto-de-desarrollo-superior-a-200-millones-de-euros\/"},"author":{"name":"Richard Wojcik","@id":"https:\/\/maslowcapital.com\/#\/schema\/person\/99ff00ee026846905cc292b48b909306"},"headline":"Maslow Capital financia la primera cartera hotelera de Selecto, la nueva plataforma hotelera de Tikehau Capital en Iberia, con un valor bruto de desarrollo superior a 200 millones de euros","datePublished":"2026-07-14T08:40:18+00:00","mainEntityOfPage":{"@id":"https:\/\/maslowcapital.com\/es\/blog\/2026\/07\/14\/maslow-capital-financia-la-primera-cartera-hotelera-de-selecto-la-nueva-plataforma-hotelera-de-tikehau-capital-en-iberia-con-un-valor-bruto-de-desarrollo-superior-a-200-millones-de-euros\/"},"wordCount":434,"publisher":{"@id":"https:\/\/maslowcapital.com\/#organization"},"image":{"@id":"https:\/\/maslowcapital.com\/es\/blog\/2026\/07\/14\/maslow-capital-financia-la-primera-cartera-hotelera-de-selecto-la-nueva-plataforma-hotelera-de-tikehau-capital-en-iberia-con-un-valor-bruto-de-desarrollo-superior-a-200-millones-de-euros\/#primaryimage"},"thumbnailUrl":"https:\/\/maslowcapital.com\/wp-content\/uploads\/2026\/06\/Malaga-Palacio-de-Congresos-large-2-scaled.png","articleSection":["Sin categorizar"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/maslowcapital.com\/es\/blog\/2026\/07\/14\/maslow-capital-financia-la-primera-cartera-hotelera-de-selecto-la-nueva-plataforma-hotelera-de-tikehau-capital-en-iberia-con-un-valor-bruto-de-desarrollo-superior-a-200-millones-de-euros\/","url":"https:\/\/maslowcapital.com\/es\/blog\/2026\/07\/14\/maslow-capital-financia-la-primera-cartera-hotelera-de-selecto-la-nueva-plataforma-hotelera-de-tikehau-capital-en-iberia-con-un-valor-bruto-de-desarrollo-superior-a-200-millones-de-euros\/","name":"Maslow Capital financia la primera cartera hotelera de Selecto, la nueva plataforma hotelera de Tikehau Capital en Iberia, con un valor bruto de desarrollo superior a 200 millones de euros | Maslow Capital","isPartOf":{"@id":"https:\/\/maslowcapital.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/maslowcapital.com\/es\/blog\/2026\/07\/14\/maslow-capital-financia-la-primera-cartera-hotelera-de-selecto-la-nueva-plataforma-hotelera-de-tikehau-capital-en-iberia-con-un-valor-bruto-de-desarrollo-superior-a-200-millones-de-euros\/#primaryimage"},"image":{"@id":"https:\/\/maslowcapital.com\/es\/blog\/2026\/07\/14\/maslow-capital-financia-la-primera-cartera-hotelera-de-selecto-la-nueva-plataforma-hotelera-de-tikehau-capital-en-iberia-con-un-valor-bruto-de-desarrollo-superior-a-200-millones-de-euros\/#primaryimage"},"thumbnailUrl":"https:\/\/maslowcapital.com\/wp-content\/uploads\/2026\/06\/Malaga-Palacio-de-Congresos-large-2-scaled.png","datePublished":"2026-07-14T08:40:18+00:00","breadcrumb":{"@id":"https:\/\/maslowcapital.com\/es\/blog\/2026\/07\/14\/maslow-capital-financia-la-primera-cartera-hotelera-de-selecto-la-nueva-plataforma-hotelera-de-tikehau-capital-en-iberia-con-un-valor-bruto-de-desarrollo-superior-a-200-millones-de-euros\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/maslowcapital.com\/es\/blog\/2026\/07\/14\/maslow-capital-financia-la-primera-cartera-hotelera-de-selecto-la-nueva-plataforma-hotelera-de-tikehau-capital-en-iberia-con-un-valor-bruto-de-desarrollo-superior-a-200-millones-de-euros\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/maslowcapital.com\/es\/blog\/2026\/07\/14\/maslow-capital-financia-la-primera-cartera-hotelera-de-selecto-la-nueva-plataforma-hotelera-de-tikehau-capital-en-iberia-con-un-valor-bruto-de-desarrollo-superior-a-200-millones-de-euros\/#primaryimage","url":"https:\/\/maslowcapital.com\/wp-content\/uploads\/2026\/06\/Malaga-Palacio-de-Congresos-large-2-scaled.png","contentUrl":"https:\/\/maslowcapital.com\/wp-content\/uploads\/2026\/06\/Malaga-Palacio-de-Congresos-large-2-scaled.png","width":2560,"height":1920},{"@type":"BreadcrumbList","@id":"https:\/\/maslowcapital.com\/es\/blog\/2026\/07\/14\/maslow-capital-financia-la-primera-cartera-hotelera-de-selecto-la-nueva-plataforma-hotelera-de-tikehau-capital-en-iberia-con-un-valor-bruto-de-desarrollo-superior-a-200-millones-de-euros\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/maslowcapital.com\/es\/"},{"@type":"ListItem","position":2,"name":"Maslow Capital financia la primera cartera hotelera de Selecto, la nueva plataforma hotelera de Tikehau Capital en Iberia, con un valor bruto de desarrollo superior a 200 millones de euros"}]},{"@type":"WebSite","@id":"https:\/\/maslowcapital.com\/#website","url":"https:\/\/maslowcapital.com\/","name":"Maslow Capital","description":"","publisher":{"@id":"https:\/\/maslowcapital.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/maslowcapital.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/maslowcapital.com\/#organization","name":"Maslow Capital","url":"https:\/\/maslowcapital.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/maslowcapital.com\/#\/schema\/logo\/image\/","url":"https:\/\/maslowcapital.com\/wp-content\/uploads\/2025\/05\/maslow-capital-logo.png","contentUrl":"https:\/\/maslowcapital.com\/wp-content\/uploads\/2025\/05\/maslow-capital-logo.png","width":328,"height":242,"caption":"Maslow Capital"},"image":{"@id":"https:\/\/maslowcapital.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/maslowcapital","https:\/\/www.linkedin.com\/company\/maslow-capital-llp\/"]},{"@type":"Person","@id":"https:\/\/maslowcapital.com\/#\/schema\/person\/99ff00ee026846905cc292b48b909306","name":"Richard Wojcik","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ab0bbd80fd18e2a52852d277779a5c3bef2d48efee7dace58782d64f83111445?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ab0bbd80fd18e2a52852d277779a5c3bef2d48efee7dace58782d64f83111445?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ab0bbd80fd18e2a52852d277779a5c3bef2d48efee7dace58782d64f83111445?s=96&d=mm&r=g","caption":"Richard Wojcik"},"url":"https:\/\/maslowcapital.com\/es\/blog\/author\/richardw\/"}]}},"_links":{"self":[{"href":"https:\/\/maslowcapital.com\/es\/wp-json\/wp\/v2\/posts\/11752","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maslowcapital.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maslowcapital.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maslowcapital.com\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/maslowcapital.com\/es\/wp-json\/wp\/v2\/comments?post=11752"}],"version-history":[{"count":4,"href":"https:\/\/maslowcapital.com\/es\/wp-json\/wp\/v2\/posts\/11752\/revisions"}],"predecessor-version":[{"id":11756,"href":"https:\/\/maslowcapital.com\/es\/wp-json\/wp\/v2\/posts\/11752\/revisions\/11756"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maslowcapital.com\/es\/wp-json\/wp\/v2\/media\/11557"}],"wp:attachment":[{"href":"https:\/\/maslowcapital.com\/es\/wp-json\/wp\/v2\/media?parent=11752"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maslowcapital.com\/es\/wp-json\/wp\/v2\/categories?post=11752"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maslowcapital.com\/es\/wp-json\/wp\/v2\/tags?post=11752"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}